{"id":2004,"date":"2026-03-23T21:26:58","date_gmt":"2026-03-24T00:26:58","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/23\/comissao-aprova-aumento-para-8-na-deducao-do-ir-em-doacoes-para-projetos-esportivos-sociais\/"},"modified":"2026-03-23T21:26:58","modified_gmt":"2026-03-24T00:26:58","slug":"comissao-aprova-aumento-para-8-na-deducao-do-ir-em-doacoes-para-projetos-esportivos-sociais","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/23\/comissao-aprova-aumento-para-8-na-deducao-do-ir-em-doacoes-para-projetos-esportivos-sociais\/","title":{"rendered":"Comiss\u00e3o aprova aumento para 8% na dedu\u00e7\u00e3o do IR em doa\u00e7\u00f5es para projetos esportivos sociais"},"content":{"rendered":"<div>\n<p>A Comiss\u00e3o do Esporte da C\u00e2mara dos Deputados aprovou proposta que eleva de 7% para 8% o limite de dedu\u00e7\u00e3o do Imposto de Renda para Pessoas F\u00edsicas (IR) em doa\u00e7\u00f5es e patroc\u00ednios destinados a projetos esportivos de inclus\u00e3o social em comunidades vulner\u00e1veis. O colegiado aprovou o substitutivo do relator, deputado Julio Cesar Ribeiro (Republicanos-DF), ao [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/03\/23\/comissao-aprova-aumento-deducao-ir-em-doacoes-para-projetos-esportivos-sociais\/\">Comiss\u00e3o aprova aumento para 8% na dedu\u00e7\u00e3o do IR em doa\u00e7\u00f5es para projetos esportivos sociais<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Comiss\u00e3o do Esporte da C\u00e2mara dos Deputados aprovou proposta que eleva de 7% para 8% o limite de dedu\u00e7\u00e3o do Imposto de Renda para Pessoas F\u00edsicas (IR) em doa\u00e7\u00f5es e patroc\u00ednios destinados a projetos esportivos de inclus\u00e3o social em comunidades vulner\u00e1veis. O colegiado aprovou o substitutivo do relator, deputado Julio Cesar Ribeiro (Republicanos-DF), ao [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2004","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=2004"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2004\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=2004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=2004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=2004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}