{"id":2005,"date":"2026-03-23T21:30:27","date_gmt":"2026-03-24T00:30:27","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/23\/deixar-de-recolher-tributo-declarado-em-dirf-nao-configura-sonegacao\/"},"modified":"2026-03-23T21:30:27","modified_gmt":"2026-03-24T00:30:27","slug":"deixar-de-recolher-tributo-declarado-em-dirf-nao-configura-sonegacao","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/23\/deixar-de-recolher-tributo-declarado-em-dirf-nao-configura-sonegacao\/","title":{"rendered":"Deixar de recolher tributo declarado em Dirf n\u00e3o configura sonega\u00e7\u00e3o"},"content":{"rendered":"<div>\n<p>A informa\u00e7\u00e3o correta sobre reten\u00e7\u00e3o de impostos prestada na Declara\u00e7\u00e3o do Imposto sobre a Renda Retido na Fonte (Dirf), mesmo sem o recolhimento aos cofres p\u00fablicos, afasta a inten\u00e7\u00e3o de fraudar o Fisco. A conduta configura apropria\u00e7\u00e3o ind\u00e9bita tribut\u00e1ria, e n\u00e3o sonega\u00e7\u00e3o fiscal. Esse foi o fundamento da 1\u00aa Turma do Tribunal Regional Federal da [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/03\/23\/deixar-de-recolher-tributo-declarado-em-dirf-nao-configura-sonegacao\/\">Deixar de recolher tributo declarado em Dirf n\u00e3o configura sonega\u00e7\u00e3o<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A informa\u00e7\u00e3o correta sobre reten\u00e7\u00e3o de impostos prestada na Declara\u00e7\u00e3o do Imposto sobre a Renda Retido na Fonte (Dirf), mesmo sem o recolhimento aos cofres p\u00fablicos, afasta a inten\u00e7\u00e3o de fraudar o Fisco. A conduta configura apropria\u00e7\u00e3o ind\u00e9bita tribut\u00e1ria, e n\u00e3o sonega\u00e7\u00e3o fiscal. Esse foi o fundamento da 1\u00aa Turma do Tribunal Regional Federal da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,42],"tags":[],"class_list":["post-2005","post","type-post","status-publish","format-standard","hentry","category-dirf","category-fisco","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=2005"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2005\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=2005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=2005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=2005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}