{"id":2019,"date":"2026-03-29T20:48:07","date_gmt":"2026-03-29T23:48:07","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/29\/simples-nacional-exige-revisao-estrategica-com-reforma\/"},"modified":"2026-03-29T20:48:07","modified_gmt":"2026-03-29T23:48:07","slug":"simples-nacional-exige-revisao-estrategica-com-reforma","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/03\/29\/simples-nacional-exige-revisao-estrategica-com-reforma\/","title":{"rendered":"Simples Nacional exige revis\u00e3o estrat\u00e9gica com reforma"},"content":{"rendered":"<div>\n<p>A Reforma Tribut\u00e1ria reacendeu o debate sobre a perman\u00eancia de empresas no Simples Nacional diante da cria\u00e7\u00e3o do IBS e da CBS e da nova l\u00f3gica de n\u00e3o cumulatividade plena prevista no novo modelo. Embora o regime simplificado tenha sido preservado por for\u00e7a constitucional, a regulamenta\u00e7\u00e3o trazida pela Lei Complementar 214\/2025 introduziu mudan\u00e7as que podem [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/03\/29\/simples-nacional-exige-revisao-estrategica-com-reforma\/\">Simples Nacional exige revis\u00e3o estrat\u00e9gica com reforma<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Reforma Tribut\u00e1ria reacendeu o debate sobre a perman\u00eancia de empresas no Simples Nacional diante da cria\u00e7\u00e3o do IBS e da CBS e da nova l\u00f3gica de n\u00e3o cumulatividade plena prevista no novo modelo. Embora o regime simplificado tenha sido preservado por for\u00e7a constitucional, a regulamenta\u00e7\u00e3o trazida pela Lei Complementar 214\/2025 introduziu mudan\u00e7as que podem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,30],"tags":[],"class_list":["post-2019","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","category-simples-nacional","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=2019"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2019\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=2019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=2019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=2019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}