{"id":2032,"date":"2026-04-01T01:04:17","date_gmt":"2026-04-01T04:04:17","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/04\/01\/mais-de-80-dos-estados-aderem-a-subsidio-a-diesel-importado\/"},"modified":"2026-04-01T01:04:17","modified_gmt":"2026-04-01T04:04:17","slug":"mais-de-80-dos-estados-aderem-a-subsidio-a-diesel-importado","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/04\/01\/mais-de-80-dos-estados-aderem-a-subsidio-a-diesel-importado\/","title":{"rendered":"Mais de 80% dos estados aderem a subs\u00eddio a diesel importado"},"content":{"rendered":"<div>\n<p>Mais de 80% dos estados brasileiros indicaram ades\u00e3o \u00e0 proposta de subs\u00eddio ao diesel importado apresentada pelo Minist\u00e9rio da Fazenda, informou a pasta em nota conjunta divulgada com o Comit\u00ea dos Secret\u00e1rios de Fazenda dos Estados e do Distrito Federal (Comsefaz). A medida busca conter a alta dos combust\u00edveis provocada pela guerra no Oriente M\u00e9dio. [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/04\/01\/mais-de-80-dos-estados-aderem-a-subsidio-a-diesel-importado\/\">Mais de 80% dos estados aderem a subs\u00eddio a diesel importado<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mais de 80% dos estados brasileiros indicaram ades\u00e3o \u00e0 proposta de subs\u00eddio ao diesel importado apresentada pelo Minist\u00e9rio da Fazenda, informou a pasta em nota conjunta divulgada com o Comit\u00ea dos Secret\u00e1rios de Fazenda dos Estados e do Distrito Federal (Comsefaz). A medida busca conter a alta dos combust\u00edveis provocada pela guerra no Oriente M\u00e9dio. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,5],"tags":[],"class_list":["post-2032","post","type-post","status-publish","format-standard","hentry","category-economia","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=2032"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2032\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=2032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=2032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=2032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}