{"id":2048,"date":"2026-04-07T21:11:43","date_gmt":"2026-04-08T00:11:43","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/04\/07\/novo-conceito-de-praca-para-calcular-ipi-retroage-em-favor-do-contribuinte\/"},"modified":"2026-04-07T21:11:43","modified_gmt":"2026-04-08T00:11:43","slug":"novo-conceito-de-praca-para-calcular-ipi-retroage-em-favor-do-contribuinte","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/04\/07\/novo-conceito-de-praca-para-calcular-ipi-retroage-em-favor-do-contribuinte\/","title":{"rendered":"Novo conceito de pra\u00e7a para calcular IPI retroage em favor do contribuinte"},"content":{"rendered":"<div>\n<p>A Lei 14.395\/2022, que restringiu o conceito de pra\u00e7a para fins de c\u00e1lculo do Imposto sobre Produtos Industrializados (IPI), n\u00e3o criou uma regra in\u00e9dita, pois apenas esclareceu normas j\u00e1 existentes. Por essa raz\u00e3o, a defini\u00e7\u00e3o mais ben\u00e9fica ao contribuinte deve ser aplicada a fatos anteriores \u00e0 vig\u00eancia da nova legisla\u00e7\u00e3o. Com base nesse entendimento, a [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/04\/07\/novo-conceito-de-praca-para-calcular-ipi-retroage-em-favor-do-contribuinte\/\">Novo conceito de pra\u00e7a para calcular IPI retroage em favor do contribuinte<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Lei 14.395\/2022, que restringiu o conceito de pra\u00e7a para fins de c\u00e1lculo do Imposto sobre Produtos Industrializados (IPI), n\u00e3o criou uma regra in\u00e9dita, pois apenas esclareceu normas j\u00e1 existentes. Por essa raz\u00e3o, a defini\u00e7\u00e3o mais ben\u00e9fica ao contribuinte deve ser aplicada a fatos anteriores \u00e0 vig\u00eancia da nova legisla\u00e7\u00e3o. Com base nesse entendimento, a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-2048","post","type-post","status-publish","format-standard","hentry","category-ipi","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=2048"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2048\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=2048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=2048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=2048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}