{"id":2099,"date":"2026-04-27T00:36:26","date_gmt":"2026-04-27T03:36:26","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/04\/27\/o-comite-gestor-ainda-esta-sem-orcamento-afirma-vice-do-orgao\/"},"modified":"2026-04-27T00:36:26","modified_gmt":"2026-04-27T03:36:26","slug":"o-comite-gestor-ainda-esta-sem-orcamento-afirma-vice-do-orgao","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/04\/27\/o-comite-gestor-ainda-esta-sem-orcamento-afirma-vice-do-orgao\/","title":{"rendered":"O Comit\u00ea Gestor ainda est\u00e1 sem or\u00e7amento, afirma vice do \u00f3rg\u00e3o"},"content":{"rendered":"<div>\n<p>O 1\u00ba vice-presidente do Comit\u00ea Gestor do IBS (Imposto sobre Bens e Servi\u00e7os), Luis Felipe Vidal Arellano, disse que o \u00f3rg\u00e3o tem trabalhado \u201csem or\u00e7amento\u201d. Segundo ele, isso atrapalha a log\u00edstica das reuni\u00f5es dos integrantes do colegiado. \u201cO Comit\u00ea Gestor ainda est\u00e1 trabalhando sem or\u00e7amento, sem recursos. As pr\u00f3prias reuni\u00f5es presenciais, que est\u00e3o acontecendo, geram [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/04\/27\/o-comite-gestor-ainda-esta-sem-orcamento-afirma-vice-do-orgao\/\">O Comit\u00ea Gestor ainda est\u00e1 sem or\u00e7amento, afirma vice do \u00f3rg\u00e3o<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O 1\u00ba vice-presidente do Comit\u00ea Gestor do IBS (Imposto sobre Bens e Servi\u00e7os), Luis Felipe Vidal Arellano, disse que o \u00f3rg\u00e3o tem trabalhado \u201csem or\u00e7amento\u201d. Segundo ele, isso atrapalha a log\u00edstica das reuni\u00f5es dos integrantes do colegiado. \u201cO Comit\u00ea Gestor ainda est\u00e1 trabalhando sem or\u00e7amento, sem recursos. As pr\u00f3prias reuni\u00f5es presenciais, que est\u00e3o acontecendo, geram [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-2099","post","type-post","status-publish","format-standard","hentry","category-reforma-tributaria","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=2099"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2099\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=2099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=2099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=2099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}