{"id":2130,"date":"2026-05-06T22:20:53","date_gmt":"2026-05-07T01:20:53","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/05\/06\/empresas-preponderantemente-exportadoras-precisarao-de-registro-previo-para-obter-suspensao-de-ipi-determina-receita-federal\/"},"modified":"2026-05-06T22:20:53","modified_gmt":"2026-05-07T01:20:53","slug":"empresas-preponderantemente-exportadoras-precisarao-de-registro-previo-para-obter-suspensao-de-ipi-determina-receita-federal","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2026\/05\/06\/empresas-preponderantemente-exportadoras-precisarao-de-registro-previo-para-obter-suspensao-de-ipi-determina-receita-federal\/","title":{"rendered":"Empresas preponderantemente exportadoras precisar\u00e3o de registro pr\u00e9vio para obter suspens\u00e3o de IPI, determina Receita Federal"},"content":{"rendered":"<div>\n<p>A Receita Federal publicou no Di\u00e1rio Oficial desta 3\u00aa feira (5.mai.2026) a Instru\u00e7\u00e3o Normativa RFB n\u00ba 2.324\/2026, que define a exig\u00eancia de registro pr\u00e9vio na entidade para que empresas preponderantemente exportadoras possam adquirir ou importar insumos com suspens\u00e3o do IPI (Imposto sobre Produtos Industrializados). O benef\u00edcio passa a depender de solicita\u00e7\u00e3o formal, an\u00e1lise documental e [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2026\/05\/06\/empresas-preponderantemente-exportadoras-precisarao-de-registro-previo-para-obter-suspensao-de-ipi-determina-receita-federal\/\">Empresas preponderantemente exportadoras precisar\u00e3o de registro pr\u00e9vio para obter suspens\u00e3o de IPI, determina Receita Federal<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Receita Federal publicou no Di\u00e1rio Oficial desta 3\u00aa feira (5.mai.2026) a Instru\u00e7\u00e3o Normativa RFB n\u00ba 2.324\/2026, que define a exig\u00eancia de registro pr\u00e9vio na entidade para que empresas preponderantemente exportadoras possam adquirir ou importar insumos com suspens\u00e3o do IPI (Imposto sobre Produtos Industrializados). O benef\u00edcio passa a depender de solicita\u00e7\u00e3o formal, an\u00e1lise documental e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2130","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=2130"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/2130\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=2130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=2130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=2130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}