{"id":770,"date":"2025-03-10T17:25:25","date_gmt":"2025-03-10T20:25:25","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/03\/10\/projeto-isenta-de-ipi-carro-comprado-por-quem-tem-cancer\/"},"modified":"2025-03-10T17:25:25","modified_gmt":"2025-03-10T20:25:25","slug":"projeto-isenta-de-ipi-carro-comprado-por-quem-tem-cancer","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/03\/10\/projeto-isenta-de-ipi-carro-comprado-por-quem-tem-cancer\/","title":{"rendered":"Projeto isenta de IPI carro comprado por quem tem c\u00e2ncer"},"content":{"rendered":"<div>\n<p>O Projeto de Lei 200\/25 isenta de Imposto sobre Produtos Industrializados (IPI) a compra de autom\u00f3veis por pessoas com c\u00e2ncer. A proposta est\u00e1 em an\u00e1lise na C\u00e2mara dos Deputados. O texto altera a Lei 8.989\/95, que j\u00e1 garante essa isen\u00e7\u00e3o a taxistas, pessoas com defici\u00eancia e pessoas com transtorno do espectro autista, entre outros. A [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/03\/10\/projeto-isenta-de-ipi-carro-comprado-por-quem-tem-cancer\/\">Projeto isenta de IPI carro comprado por quem tem c\u00e2ncer<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Projeto de Lei 200\/25 isenta de Imposto sobre Produtos Industrializados (IPI) a compra de autom\u00f3veis por pessoas com c\u00e2ncer. A proposta est\u00e1 em an\u00e1lise na C\u00e2mara dos Deputados. O texto altera a Lei 8.989\/95, que j\u00e1 garante essa isen\u00e7\u00e3o a taxistas, pessoas com defici\u00eancia e pessoas com transtorno do espectro autista, entre outros. A [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,46,5],"tags":[],"class_list":["post-770","post","type-post","status-publish","format-standard","hentry","category-ipi","category-isencao-de-ipi","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}