{"id":825,"date":"2025-03-27T18:58:56","date_gmt":"2025-03-27T21:58:56","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/03\/27\/empresas-de-turismo-e-eventos-pedem-continuidade-de-beneficios-fiscais-concedidos-na-pandemia\/"},"modified":"2025-03-27T18:58:56","modified_gmt":"2025-03-27T21:58:56","slug":"empresas-de-turismo-e-eventos-pedem-continuidade-de-beneficios-fiscais-concedidos-na-pandemia","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/03\/27\/empresas-de-turismo-e-eventos-pedem-continuidade-de-beneficios-fiscais-concedidos-na-pandemia\/","title":{"rendered":"Empresas de turismo e eventos pedem continuidade de benef\u00edcios fiscais concedidos na pandemia"},"content":{"rendered":"<div>\n<p>Representantes dos setores de turismo e eventos afirmaram nesta quinta-feira (27), durante comiss\u00e3o geral no Plen\u00e1rio da C\u00e2mara dos Deputados, que o fim antecipado do programa de apoio financeiro ao setor pode comprometer a plena recupera\u00e7\u00e3o financeira das empresas. Eles negociam com o governo federal a prorroga\u00e7\u00e3o dos benef\u00edcios fiscais a partir da devolu\u00e7\u00e3o de [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/03\/27\/empresas-de-turismo-e-eventos-pedem-continuidade-de-beneficios-fiscais-concedidos-na-pandemia\/\">Empresas de turismo e eventos pedem continuidade de benef\u00edcios fiscais concedidos na pandemia<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Representantes dos setores de turismo e eventos afirmaram nesta quinta-feira (27), durante comiss\u00e3o geral no Plen\u00e1rio da C\u00e2mara dos Deputados, que o fim antecipado do programa de apoio financeiro ao setor pode comprometer a plena recupera\u00e7\u00e3o financeira das empresas. Eles negociam com o governo federal a prorroga\u00e7\u00e3o dos benef\u00edcios fiscais a partir da devolu\u00e7\u00e3o de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-825","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}