{"id":884,"date":"2025-04-10T22:02:26","date_gmt":"2025-04-11T01:02:26","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/10\/e-financeira-transmissao-do-modo-sincrono-sera-desativada\/"},"modified":"2025-04-10T22:02:26","modified_gmt":"2025-04-11T01:02:26","slug":"e-financeira-transmissao-do-modo-sincrono-sera-desativada","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/10\/e-financeira-transmissao-do-modo-sincrono-sera-desativada\/","title":{"rendered":"e-Financeira: Transmiss\u00e3o do modo s\u00edncrono ser\u00e1 desativada"},"content":{"rendered":"<div>\n<p>Ap\u00f3s a atualiza\u00e7\u00e3o do modo de transmiss\u00e3o realizada no dia 25\/o3\/2025, a transmiss\u00e3o de lotes e consultas a dados de evento no modo ass\u00edncrono foi implantada na produ\u00e7\u00e3o. Haver\u00e1 um per\u00edodo de transi\u00e7\u00e3o no primeiro semestre de 2025. Durante este per\u00edodo de transi\u00e7\u00e3o, a transmiss\u00e3o dos eventos existentes atualmente poder\u00e1 ser feita nos modos s\u00edncrono [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/04\/10\/e-financeira-transmissao-do-modo-sincrono-sera-desativada\/\">e-Financeira: Transmiss\u00e3o do modo s\u00edncrono ser\u00e1 desativada<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a atualiza\u00e7\u00e3o do modo de transmiss\u00e3o realizada no dia 25\/o3\/2025, a transmiss\u00e3o de lotes e consultas a dados de evento no modo ass\u00edncrono foi implantada na produ\u00e7\u00e3o. Haver\u00e1 um per\u00edodo de transi\u00e7\u00e3o no primeiro semestre de 2025. Durante este per\u00edodo de transi\u00e7\u00e3o, a transmiss\u00e3o dos eventos existentes atualmente poder\u00e1 ser feita nos modos s\u00edncrono [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-884","post","type-post","status-publish","format-standard","hentry","category-e-financeira","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=884"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/884\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}