{"id":901,"date":"2025-04-16T23:10:08","date_gmt":"2025-04-17T02:10:08","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/16\/ministro-estuda-aumentar-teto-do-mei-e-adotar-tabela-progressiva-para-categoria-defasagem-chega-a-122\/"},"modified":"2025-04-16T23:10:08","modified_gmt":"2025-04-17T02:10:08","slug":"ministro-estuda-aumentar-teto-do-mei-e-adotar-tabela-progressiva-para-categoria-defasagem-chega-a-122","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/16\/ministro-estuda-aumentar-teto-do-mei-e-adotar-tabela-progressiva-para-categoria-defasagem-chega-a-122\/","title":{"rendered":"Ministro estuda aumentar teto do MEI e adotar tabela progressiva para categoria; defasagem chega a 122%"},"content":{"rendered":"<div>\n<p>O governo federal avalia aumentar o limite de faturamento anual do Microempreendedor Individual (MEI) , atualmente fixado em R$ 81 mil. A proposta foi confirmada nesta segunda-feira (14) pelo ministro M\u00e1rcio Fran\u00e7a, da pasta do Empreendedorismo, Microempresa e Empresa de Pequeno Porte, durante evento realizado na sede da UGT, em S\u00e3o Paulo. Segundo ele, o [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/04\/16\/ministro-estuda-aumentar-teto-do-mei-e-adotar-tabela-progressiva-para-categoria-defasagem-chega-a-122\/\">Ministro estuda aumentar teto do MEI e adotar tabela progressiva para categoria; defasagem chega a 122%<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O governo federal avalia aumentar o limite de faturamento anual do Microempreendedor Individual (MEI) , atualmente fixado em R$ 81 mil. A proposta foi confirmada nesta segunda-feira (14) pelo ministro M\u00e1rcio Fran\u00e7a, da pasta do Empreendedorismo, Microempresa e Empresa de Pequeno Porte, durante evento realizado na sede da UGT, em S\u00e3o Paulo. Segundo ele, o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,11],"tags":[],"class_list":["post-901","post","type-post","status-publish","format-standard","hentry","category-economia","category-mei","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=901"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/901\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}