{"id":924,"date":"2025-04-24T23:38:08","date_gmt":"2025-04-25T02:38:08","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/24\/agu-sugere-novo-modelo-para-julgamento-de-tributos\/"},"modified":"2025-04-24T23:38:08","modified_gmt":"2025-04-25T02:38:08","slug":"agu-sugere-novo-modelo-para-julgamento-de-tributos","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/24\/agu-sugere-novo-modelo-para-julgamento-de-tributos\/","title":{"rendered":"AGU sugere novo modelo para julgamento de tributos"},"content":{"rendered":"<div>\n<p>O Conselho Nacional de Justi\u00e7a (CNJ) instituiu um grupo de trabalho para desenvolver um anteprojeto de reforma processual tribut\u00e1ria, com o objetivo de adaptar o sistema judici\u00e1rio \u00e0s mudan\u00e7as introduzidas pela Emenda Constitucional n\u00ba 132\/2023. A proposta central \u00e9 a cria\u00e7\u00e3o de um foro nacional especializado para julgar quest\u00f5es relacionadas \u00e0 Contribui\u00e7\u00e3o sobre Bens e [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/04\/24\/agu-sugere-novo-modelo-para-julgamento-de-tributos\/\">AGU sugere novo modelo para julgamento de tributos<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Nacional de Justi\u00e7a (CNJ) instituiu um grupo de trabalho para desenvolver um anteprojeto de reforma processual tribut\u00e1ria, com o objetivo de adaptar o sistema judici\u00e1rio \u00e0s mudan\u00e7as introduzidas pela Emenda Constitucional n\u00ba 132\/2023. A proposta central \u00e9 a cria\u00e7\u00e3o de um foro nacional especializado para julgar quest\u00f5es relacionadas \u00e0 Contribui\u00e7\u00e3o sobre Bens e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-924","post","type-post","status-publish","format-standard","hentry","category-tributos","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=924"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/924\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}