{"id":934,"date":"2025-04-28T18:03:39","date_gmt":"2025-04-28T21:03:39","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/28\/portal-de-servicos-do-contribuinte-agora-permite-a-representacao-digital-por-terceiros\/"},"modified":"2025-04-28T18:03:39","modified_gmt":"2025-04-28T21:03:39","slug":"portal-de-servicos-do-contribuinte-agora-permite-a-representacao-digital-por-terceiros","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/28\/portal-de-servicos-do-contribuinte-agora-permite-a-representacao-digital-por-terceiros\/","title":{"rendered":"Portal de Servi\u00e7os do Contribuinte agora permite a representa\u00e7\u00e3o digital por terceiros"},"content":{"rendered":"<div>\n<p>O Portal de Servi\u00e7os do Contribuinte acaba de receber duas novidades que v\u00e3o tornar a vida do usu\u00e1rio mais pr\u00e1tica: o login com a conta Gov.br e a possibilidade de representar terceiros diretamente pelo sistema. A integra\u00e7\u00e3o com o Gov.br vai permitir o acesso unificado a todos os servi\u00e7os dispon\u00edveis tanto no Portal quanto no [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/04\/28\/portal-de-servicos-do-contribuinte-agora-permite-a-representacao-digital-por-terceiros\/\">Portal de Servi\u00e7os do Contribuinte agora permite a representa\u00e7\u00e3o digital por terceiros<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O Portal de Servi\u00e7os do Contribuinte acaba de receber duas novidades que v\u00e3o tornar a vida do usu\u00e1rio mais pr\u00e1tica: o login com a conta Gov.br e a possibilidade de representar terceiros diretamente pelo sistema. A integra\u00e7\u00e3o com o Gov.br vai permitir o acesso unificado a todos os servi\u00e7os dispon\u00edveis tanto no Portal quanto no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,7],"tags":[],"class_list":["post-934","post","type-post","status-publish","format-standard","hentry","category-e-cac","category-rfb","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=934"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/934\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}