{"id":940,"date":"2025-04-30T20:10:58","date_gmt":"2025-04-30T23:10:58","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/30\/trf3-concede-isencao-do-ipi-na-compra-de-carro-zero-quilometro-a-pessoa-com-deficiencia-que-recebe-bpc\/"},"modified":"2025-04-30T20:10:58","modified_gmt":"2025-04-30T23:10:58","slug":"trf3-concede-isencao-do-ipi-na-compra-de-carro-zero-quilometro-a-pessoa-com-deficiencia-que-recebe-bpc","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/30\/trf3-concede-isencao-do-ipi-na-compra-de-carro-zero-quilometro-a-pessoa-com-deficiencia-que-recebe-bpc\/","title":{"rendered":"TRF3 concede isen\u00e7\u00e3o do IPI na compra de carro zero-quil\u00f4metro a pessoa com defici\u00eancia que recebe BPC"},"content":{"rendered":"<div>\n<p>A Quarta Turma do Tribunal Regional Federal da 3\u00aa Regi\u00e3o (TRF3) assegurou a uma pessoa com defici\u00eancia que recebe o Benef\u00edcio de Presta\u00e7\u00e3o Continuada (BPC) o direito \u00e0 isen\u00e7\u00e3o do Imposto sobre Produtos Industrializados (IPI) na aquisi\u00e7\u00e3o de ve\u00edculo zero-quil\u00f4metro. Com base no voto da relatora, desembargadora federal Leila Paiva, o colegiado entendeu que a [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/04\/30\/trf3-concede-isencao-do-ipi-na-compra-de-carro-zero-quilometro-a-pessoa-com-deficiencia-que-recebe-bpc\/\">TRF3 concede isen\u00e7\u00e3o do IPI na compra de carro zero-quil\u00f4metro a pessoa com defici\u00eancia que recebe BPC<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Quarta Turma do Tribunal Regional Federal da 3\u00aa Regi\u00e3o (TRF3) assegurou a uma pessoa com defici\u00eancia que recebe o Benef\u00edcio de Presta\u00e7\u00e3o Continuada (BPC) o direito \u00e0 isen\u00e7\u00e3o do Imposto sobre Produtos Industrializados (IPI) na aquisi\u00e7\u00e3o de ve\u00edculo zero-quil\u00f4metro. Com base no voto da relatora, desembargadora federal Leila Paiva, o colegiado entendeu que a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-940","post","type-post","status-publish","format-standard","hentry","category-ipi","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=940"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/940\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}