{"id":942,"date":"2025-04-30T20:19:37","date_gmt":"2025-04-30T23:19:37","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/30\/repetitivos-do-stj-traz-julgados-sobre-credito-de-ipi-na-compra-de-insumos-para-produtos-imunes\/"},"modified":"2025-04-30T20:19:37","modified_gmt":"2025-04-30T23:19:37","slug":"repetitivos-do-stj-traz-julgados-sobre-credito-de-ipi-na-compra-de-insumos-para-produtos-imunes","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/04\/30\/repetitivos-do-stj-traz-julgados-sobre-credito-de-ipi-na-compra-de-insumos-para-produtos-imunes\/","title":{"rendered":"Repetitivos do STJ traz julgados sobre cr\u00e9dito de IPI na compra de insumos para produtos imunes"},"content":{"rendered":"<div>\n<p>A Secretaria de Biblioteca e Jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ) atualizou a base de dados de Repetitivos e IACs Anotados. Foram inclu\u00eddas informa\u00e7\u00f5es a respeito do julgamento dos Recursos Especiais 1.976.618 e 1.995.220, classificados no ramo do direito tribut\u00e1rio, no assunto Imposto sobre Produtos Industrializados (IPI). Os ac\u00f3rd\u00e3os estabelecem o direito ao creditamento [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/04\/30\/repetitivos-do-stj-traz-julgados-sobre-credito-de-ipi-na-compra-de-insumos-para-produtos-imunes\/\">Repetitivos do STJ traz julgados sobre cr\u00e9dito de IPI na compra de insumos para produtos imunes<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Biblioteca e Jurisprud\u00eancia do Superior Tribunal de Justi\u00e7a (STJ) atualizou a base de dados de Repetitivos e IACs Anotados. Foram inclu\u00eddas informa\u00e7\u00f5es a respeito do julgamento dos Recursos Especiais 1.976.618 e 1.995.220, classificados no ramo do direito tribut\u00e1rio, no assunto Imposto sobre Produtos Industrializados (IPI). Os ac\u00f3rd\u00e3os estabelecem o direito ao creditamento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-942","post","type-post","status-publish","format-standard","hentry","category-ipi","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=942"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/942\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}