{"id":981,"date":"2025-05-14T18:24:51","date_gmt":"2025-05-14T21:24:51","guid":{"rendered":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/05\/14\/decisao-judicial-concede-direito-a-devolucao-do-ipi-pago-por-pessoas-com-deficiencia-que-adquiriram-automoveis-a-gasolina-no-inicio-dos-anos-2000\/"},"modified":"2025-05-14T18:24:51","modified_gmt":"2025-05-14T21:24:51","slug":"decisao-judicial-concede-direito-a-devolucao-do-ipi-pago-por-pessoas-com-deficiencia-que-adquiriram-automoveis-a-gasolina-no-inicio-dos-anos-2000","status":"publish","type":"post","link":"https:\/\/cscontabil.cnt.br\/index.php\/2025\/05\/14\/decisao-judicial-concede-direito-a-devolucao-do-ipi-pago-por-pessoas-com-deficiencia-que-adquiriram-automoveis-a-gasolina-no-inicio-dos-anos-2000\/","title":{"rendered":"Decis\u00e3o judicial concede direito \u00e0 devolu\u00e7\u00e3o do IPI pago por pessoas com defici\u00eancia que adquiriram autom\u00f3veis a gasolina no in\u00edcio dos anos 2000"},"content":{"rendered":"<div>\n<p>Se voc\u00ea se enquadra nos requisitos de benefici\u00e1rio, seu pedido deve ser efetuado na Justi\u00e7a Federal. A Uni\u00e3o foi condenada, nos autos da a\u00e7\u00e3o civil p\u00fablica n. 0018178-11.2000.4.03.6100, a devolver o IPI incidente na venda de ve\u00edculo, com qualquer combust\u00edvel, para pessoas com defici\u00eancia, nos per\u00edodos de 1\u00ba de janeiro a 25 de junho de [\u2026]<\/p>\n<p>O post <a href=\"https:\/\/mauronegruni.com.br\/2025\/05\/14\/decisao-judicial-concede-direito-a-devolucao-do-ipi-pago-por-pessoas-com-deficiencia-que-adquiriram-automoveis-a-gasolina-no-inicio-dos-anos-2000\/\">Decis\u00e3o judicial concede direito \u00e0 devolu\u00e7\u00e3o do IPI pago por pessoas com defici\u00eancia que adquiriram autom\u00f3veis a gasolina no in\u00edcio dos anos 2000<\/a> apareceu primeiro em <a href=\"https:\/\/mauronegruni.com.br\/\">Mauro Negruni<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea se enquadra nos requisitos de benefici\u00e1rio, seu pedido deve ser efetuado na Justi\u00e7a Federal. A Uni\u00e3o foi condenada, nos autos da a\u00e7\u00e3o civil p\u00fablica n. 0018178-11.2000.4.03.6100, a devolver o IPI incidente na venda de ve\u00edculo, com qualquer combust\u00edvel, para pessoas com defici\u00eancia, nos per\u00edodos de 1\u00ba de janeiro a 25 de junho de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32],"tags":[],"class_list":["post-981","post","type-post","status-publish","format-standard","hentry","category-ipi","entry"],"_links":{"self":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/comments?post=981"}],"version-history":[{"count":0,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/posts\/981\/revisions"}],"wp:attachment":[{"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/media?parent=981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/categories?post=981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cscontabil.cnt.br\/index.php\/wp-json\/wp\/v2\/tags?post=981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}